{"id":795,"date":"2021-02-15T16:25:37","date_gmt":"2021-02-15T16:25:37","guid":{"rendered":"https:\/\/www.dedalus.com\/latam\/?page_id=795"},"modified":"2021-07-15T10:40:17","modified_gmt":"2021-07-15T10:40:17","slug":"consulting","status":"publish","type":"page","link":"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/","title":{"rendered":"Consulting"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":1004,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"class_list":["post-795","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Consulting - Dedalus LATAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consulting\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/\" \/>\n<meta property=\"og:site_name\" content=\"Dedalus LATAM\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-15T10:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dedalus.com\/latam\/wp-content\/uploads\/sites\/23\/2023\/12\/logo_Site-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/\",\"url\":\"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/\",\"name\":\"Consulting - Dedalus LATAM\",\"isPartOf\":{\"@id\":\"https:\/\/www.dedalus.com\/latam\/en\/#website\"},\"datePublished\":\"2021-02-15T16:25:37+00:00\",\"dateModified\":\"2021-07-15T10:40:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dedalus.com\/latam\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our Offer\",\"item\":\"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Services\",\"item\":\"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Consulting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dedalus.com\/latam\/en\/#website\",\"url\":\"https:\/\/www.dedalus.com\/latam\/en\/\",\"name\":\"Dedalus LATAM\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.dedalus.com\/latam\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dedalus.com\/latam\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dedalus.com\/latam\/en\/#organization\",\"name\":\"Dedalus LATAM\",\"url\":\"https:\/\/www.dedalus.com\/latam\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dedalus.com\/latam\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dedalus.com\/latam\/wp-content\/uploads\/sites\/23\/2023\/12\/logo_Site-Favicon.jpg\",\"contentUrl\":\"https:\/\/www.dedalus.com\/latam\/wp-content\/uploads\/sites\/23\/2023\/12\/logo_Site-Favicon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Dedalus LATAM\"},\"image\":{\"@id\":\"https:\/\/www.dedalus.com\/latam\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Consulting - Dedalus LATAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/","og_locale":"en_US","og_type":"article","og_title":"Consulting","og_url":"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/","og_site_name":"Dedalus LATAM","article_modified_time":"2021-07-15T10:40:17+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.dedalus.com\/latam\/wp-content\/uploads\/sites\/23\/2023\/12\/logo_Site-Image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/","url":"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/","name":"Consulting - Dedalus LATAM","isPartOf":{"@id":"https:\/\/www.dedalus.com\/latam\/en\/#website"},"datePublished":"2021-02-15T16:25:37+00:00","dateModified":"2021-07-15T10:40:17+00:00","breadcrumb":{"@id":"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/consulting\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dedalus.com\/latam\/en\/"},{"@type":"ListItem","position":2,"name":"Our Offer","item":"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/"},{"@type":"ListItem","position":3,"name":"Services","item":"https:\/\/www.dedalus.com\/latam\/en\/our-solutions\/services\/"},{"@type":"ListItem","position":4,"name":"Consulting"}]},{"@type":"WebSite","@id":"https:\/\/www.dedalus.com\/latam\/en\/#website","url":"https:\/\/www.dedalus.com\/latam\/en\/","name":"Dedalus LATAM","description":"","publisher":{"@id":"https:\/\/www.dedalus.com\/latam\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dedalus.com\/latam\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dedalus.com\/latam\/en\/#organization","name":"Dedalus LATAM","url":"https:\/\/www.dedalus.com\/latam\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dedalus.com\/latam\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.dedalus.com\/latam\/wp-content\/uploads\/sites\/23\/2023\/12\/logo_Site-Favicon.jpg","contentUrl":"https:\/\/www.dedalus.com\/latam\/wp-content\/uploads\/sites\/23\/2023\/12\/logo_Site-Favicon.jpg","width":512,"height":512,"caption":"Dedalus LATAM"},"image":{"@id":"https:\/\/www.dedalus.com\/latam\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.dedalus.com\/latam\/en\/wp-json\/wp\/v2\/pages\/795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dedalus.com\/latam\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dedalus.com\/latam\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dedalus.com\/latam\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dedalus.com\/latam\/en\/wp-json\/wp\/v2\/comments?post=795"}],"version-history":[{"count":16,"href":"https:\/\/www.dedalus.com\/latam\/en\/wp-json\/wp\/v2\/pages\/795\/revisions"}],"predecessor-version":[{"id":2493,"href":"https:\/\/www.dedalus.com\/latam\/en\/wp-json\/wp\/v2\/pages\/795\/revisions\/2493"}],"up":[{"embeddable":true,"href":"https:\/\/www.dedalus.com\/latam\/en\/wp-json\/wp\/v2\/pages\/1004"}],"wp:attachment":[{"href":"https:\/\/www.dedalus.com\/latam\/en\/wp-json\/wp\/v2\/media?parent=795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}